{"id":475,"date":"2017-07-08T12:58:21","date_gmt":"2017-07-08T19:58:21","guid":{"rendered":"https:\/\/sites.ewu.edu\/wsc\/?page_id=475"},"modified":"2017-07-08T12:58:21","modified_gmt":"2017-07-08T19:58:21","slug":"core-events","status":"publish","type":"page","link":"https:\/\/inside.ewu.edu\/wagec\/events\/core-events\/","title":{"rendered":"Core Events"},"content":{"rendered":"<p>1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1<\/p>\n","protected":false},"author":131,"featured_media":0,"parent":171,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"wpo365_audiences":[],"wpo365_private":false,"footnotes":""},"class_list":["post-475","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/inside.ewu.edu\/wagec\/wp-json\/wp\/v2\/pages\/475"}],"collection":[{"href":"https:\/\/inside.ewu.edu\/wagec\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/inside.ewu.edu\/wagec\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/inside.ewu.edu\/wagec\/wp-json\/wp\/v2\/users\/131"}],"replies":[{"embeddable":true,"href":"https:\/\/inside.ewu.edu\/wagec\/wp-json\/wp\/v2\/comments?post=475"}],"version-history":[{"count":0,"href":"https:\/\/inside.ewu.edu\/wagec\/wp-json\/wp\/v2\/pages\/475\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/inside.ewu.edu\/wagec\/wp-json\/wp\/v2\/pages\/171"}],"wp:attachment":[{"href":"https:\/\/inside.ewu.edu\/wagec\/wp-json\/wp\/v2\/media?parent=475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}