{"id":35671,"date":"2024-05-10T14:14:50","date_gmt":"2024-05-10T21:14:50","guid":{"rendered":"https:\/\/inside.ewu.edu\/financialservices\/?page_id=35671"},"modified":"2026-04-30T09:13:54","modified_gmt":"2026-04-30T16:13:54","slug":"financial-reports","status":"publish","type":"page","link":"https:\/\/inside.ewu.edu\/financialservices\/office-of-controller\/financial-reports\/","title":{"rendered":"Financial Reports"},"content":{"rendered":"<div class=\"gb-container gb-container-d117f309\"><div class=\"gb-inside-container\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-3da123a4\">\n<div class=\"gb-grid-column gb-grid-column-c5c6ca4d\"><div class=\"gb-container gb-container-c5c6ca4d\"><div class=\"gb-inside-container\">\n\n<h1 class=\"gb-headline gb-headline-fc558012 gb-headline-text\">Financial Reports and Reviews<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Office of Controller<\/h2>\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-fdab2790\">\n\n<h3 class=\"wp-block-heading has-text-align-center\">The Office of Controller is responsible for preparing the university financial statements. The statements are published in an annual financial report. Additional hard copies may be available by contacting us at Phone: (509) 359-6816<\/h3>\n\n<\/div>\n\n<div class=\"gb-container gb-container-4b1715fb alignwide\">\n\n<h2 class=\"wp-block-heading has-text-align-center\">Eastern Washington University<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Financial Reports<\/h2>\n\n\n\n<p class=\"has-text-align-center\"><strong>Audited Financial Statements<\/strong><\/p>\n\n\n\n<div style=\"height:4px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-24af9111\">\n<div class=\"gb-grid-column gb-grid-column-0875c0d6\"><div class=\"gb-container gb-container-0875c0d6\">\n\n<p class=\"has-text-align-left\"><a href=\"https:\/\/inside.ewu.edu\/officeofcontroller\/wp-content\/uploads\/sites\/175\/2026\/02\/FY25-financial-report-final-web.pdf\" data-type=\"link\" data-id=\"https:\/\/inside.ewu.edu\/officeofcontroller\/wp-content\/uploads\/sites\/175\/2026\/02\/FY25-financial-report-final-web.pdf\">Financial Report 2025<\/a><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-b177d77a\"><div class=\"gb-container gb-container-b177d77a\">\n\n<p class=\"has-text-align-left\"><a href=\"https:\/\/inside.ewu.edu\/financialservices\/wp-content\/uploads\/sites\/44\/2025\/03\/OOC-FY24-Financial-Services-web-version.pdf\" data-type=\"link\" data-id=\"https:\/\/inside.ewu.edu\/financialservices\/wp-content\/uploads\/sites\/44\/2025\/03\/OOC-FY24-Financial-Services-web-version.pdf\">Financial Report 2024<\/a><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-9a39e5c0\"><div class=\"gb-container gb-container-9a39e5c0\">\n\n<p class=\"has-text-align-left\"><a href=\"https:\/\/in.ewu.edu\/financialservices\/wp-content\/uploads\/sites\/44\/2024\/02\/FY23-EWU-FS-web-version-final-1.pdf\" data-type=\"link\" data-id=\"https:\/\/in.ewu.edu\/financialservices\/wp-content\/uploads\/sites\/44\/2024\/02\/FY23-EWU-FS-web-version-final-1.pdf\">Financial Report 2023<\/a><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-c450e53d\"><div class=\"gb-container gb-container-c450e53d\">\n\n<p><a href=\"https:\/\/in.ewu.edu\/financialservices\/wp-content\/uploads\/sites\/44\/2023\/03\/FY22-EWU-report-web-version.pdf\" data-type=\"link\" data-id=\"https:\/\/in.ewu.edu\/financialservices\/wp-content\/uploads\/sites\/44\/2023\/03\/FY22-EWU-report-web-version.pdf\">Financial Report 2022<\/a><\/p>\n\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-19b809f2\"><\/div>\n\n<div class=\"gb-container gb-container-0db3aa10\">\n\n<h2 class=\"wp-block-heading has-text-align-center\">Financial Reviews<\/h2>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-d3570ead\">\n<div class=\"gb-grid-column gb-grid-column-a13e98bf\"><div class=\"gb-container gb-container-a13e98bf\">\n\n<p><a href=\"https:\/\/inside.ewu.edu\/officeofcontroller\/wp-content\/uploads\/sites\/175\/2026\/04\/2025-Financial-Review-BOT.pdf\">FY25 Financial Review<\/a><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-552ac92a\"><div class=\"gb-container gb-container-552ac92a\">\n\n<p><a href=\"https:\/\/inside.ewu.edu\/officeofcontroller\/wp-content\/uploads\/sites\/175\/2026\/04\/2024-Financial-Review-Final.pdf\">FY24 Financial Review<\/a><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-a00ae7ac\"><div class=\"gb-container gb-container-a00ae7ac\">\n\n<p><a href=\"https:\/\/inside.ewu.edu\/officeofcontroller\/wp-content\/uploads\/sites\/175\/2026\/04\/2023-Financial-Review-2.2024.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">FY23 Financial Review<\/a><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-7ef61085\"><div class=\"gb-container gb-container-7ef61085\">\n\n<p><a href=\"https:\/\/inside.ewu.edu\/officeofcontroller\/wp-content\/uploads\/sites\/175\/2026\/04\/2022-Financial-Review-.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">FY22 Financial Review<\/a><\/p>\n\n<\/div><\/div>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">NCAA Intercollegiate Agreed Upon Procedures Reports<\/h3>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\"><div class=\"gb-grid-wrapper gb-grid-wrapper-9f75cced\">\n<div class=\"gb-grid-column gb-grid-column-53da2c9a\"><div class=\"gb-container gb-container-53da2c9a\">\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/inside.ewu.edu\/financialservices\/wp-content\/uploads\/sites\/44\/2025\/02\/OOC-Final-Signed-Athletics-AUP-Report-FY24.pdf\">FY24 Athletics AUP Report<\/a><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-bccde0e0\"><div class=\"gb-container gb-container-bccde0e0\">\n\n<p><a href=\"https:\/\/in.ewu.edu\/financialservices\/wp-content\/uploads\/sites\/44\/2024\/02\/EWU-Athletics-AUP-Final-2023-Report.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">FY23 Athletics AUP Report<\/a><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-53e447bb\"><div class=\"gb-container gb-container-53e447bb\">\n\n<p><a href=\"https:\/\/in.ewu.edu\/financialservices\/wp-content\/uploads\/sites\/44\/2023\/03\/NCAA-Agreed-Upon-Procedures-Report-FY22.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">FY22 Athletics AUP Report<\/a><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-b2d972ba\"><div class=\"gb-container gb-container-b2d972ba\">\n\n<p><a href=\"https:\/\/in.ewu.edu\/financialservices\/wp-content\/uploads\/sites\/44\/2022\/03\/FY21-EWU-Intercollegiate-Athletics-NCAA-AUP-Report.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">FY21 Athletics AUP Report<\/a><\/p>\n\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">EWU Debt Compliance Reports<\/h3>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-6624ad08\">\n<div class=\"gb-grid-column gb-grid-column-7a02bb26\"><div class=\"gb-container gb-container-7a02bb26\">\n\n<p class=\"has-text-align-right\"><a href=\"https:\/\/inside.ewu.edu\/financialservices\/wp-content\/uploads\/sites\/44\/2025\/06\/2024-Debt-Compliance-Report.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">FY24 Debt Compliance Report<\/a><\/p>\n\n<\/div><\/div>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-e8c60609\">\n<div class=\"gb-grid-column gb-grid-column-9f4c388a\"><div class=\"gb-container gb-container-9f4c388a\">\n\n<h3 class=\"wp-block-heading\"><strong>Contact Us<\/strong><\/h3>\n\n\n\n<p>Donna Barney<\/p>\n\n\n\n<p>Phone: <a href=\"tel:509.359.6816\">509.359.6816<\/a><\/p>\n\n\n\n<p>Fax: <a href=\"tel:509.359.6869\">509.359.6869<\/a><\/p>\n\n\n\n<p>Email: <a href=\"mailto:dbarney2@ewu.edu\">dbarney2@ewu.edu<\/a><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-6ce58d9c\"><div class=\"gb-container gb-container-6ce58d9c\">\n\n<h3 class=\"wp-block-heading\">Mailing Address:<\/h3>\n\n\n\n<p>319 Showalter Hall<br>Cheney, WA 99004<br>Office Hours: 8AM &#8211; 5PM Monday -Friday<\/p>\n\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Office of Controller is responsible for preparing the university financial statements. The statements are published in an annual financial report. Additional hard copies may be available by contacting us at Phone: (509) 359-6816 Eastern Washington University Financial Reports Audited Financial Statements Financial Reviews NCAA Intercollegiate Agreed Upon Procedures Reports EWU Debt Compliance Reports<\/p>\n","protected":false},"author":33702,"featured_media":0,"parent":35626,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"wpo365_audiences":[],"wpo365_private":false,"footnotes":""},"class_list":["post-35671","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/inside.ewu.edu\/financialservices\/wp-json\/wp\/v2\/pages\/35671"}],"collection":[{"href":"https:\/\/inside.ewu.edu\/financialservices\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/inside.ewu.edu\/financialservices\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/inside.ewu.edu\/financialservices\/wp-json\/wp\/v2\/users\/33702"}],"replies":[{"embeddable":true,"href":"https:\/\/inside.ewu.edu\/financialservices\/wp-json\/wp\/v2\/comments?post=35671"}],"version-history":[{"count":25,"href":"https:\/\/inside.ewu.edu\/financialservices\/wp-json\/wp\/v2\/pages\/35671\/revisions"}],"predecessor-version":[{"id":37876,"href":"https:\/\/inside.ewu.edu\/financialservices\/wp-json\/wp\/v2\/pages\/35671\/revisions\/37876"}],"up":[{"embeddable":true,"href":"https:\/\/inside.ewu.edu\/financialservices\/wp-json\/wp\/v2\/pages\/35626"}],"wp:attachment":[{"href":"https:\/\/inside.ewu.edu\/financialservices\/wp-json\/wp\/v2\/media?parent=35671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}